{"id":2384,"date":"2022-04-22T12:04:51","date_gmt":"2022-04-22T10:04:51","guid":{"rendered":"https:\/\/staging.mobisys.com\/?page_id=2384"},"modified":"2025-08-08T10:05:59","modified_gmt":"2025-08-08T08:05:59","slug":"msb-five","status":"publish","type":"page","link":"https:\/\/mobisys.com\/en\/msb-five\/","title":{"rendered":"MSB FIVE"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;15%&#8221; bottom_padding_phone=&#8221;15%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient=&#8221;linear-gradient(95deg, rgba(0,133,202,0.53) 0%, rgba(0,133,202,0.869) 29%, rgba(0,118,128,0.878) 86%)&#8221; advanced_gradient_angle=&#8221;95&#8243; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#000000&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;advanced&#8221; advanced_gradient_display_type=&#8221;linear&#8221; shape_type=&#8221;tilt_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; el_class=&#8221;back-button&#8221; el_id=&#8221;back-button&#8221; text_direction=&#8221;default&#8221;]<a href=\"https:\/\/mobisys.com\/en\/software-products\/\">\u00ab Software Products<\/a>[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"iwithtext\">\n<div class=\"iwt-text\">\n<h1><span style=\"color: #000000;\">MSB FIVE for <strong>mobile SAP processes<\/strong><\/span><\/h1>\n<\/div>\n<\/div>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; el_class=&#8221;Einleitung&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\">\n<p>User-guided applications fast &amp; easy<\/p>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#000000&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; left_margin_phone=&#8221;0&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;Einleitung&#8221;]\n<div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\">MSB FIVE signifies for development speed and flexibility. With minimum development effort, Apps are created which are adapted to individual business processes. With MSB FIVE you react flexibly and quickly to the constantly changing requirements of digitization. Your benefit with MSB FIVE:<\/div>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-check\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-3\" data-spacing=\"15px\" data-alignment=\"left\"> \n<ul>\n<li>Clear, modern screens with responsive design<\/li>\n<li>Smart screen interaction and optimal user experience for end users<\/li>\n<\/ul>\n <\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;10%&#8221; bottom_margin=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<h2 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"28\" data-lineheight=\"38.92px\">App development <span style=\"color: #0085ca;\"><strong>in 30 minutes<\/strong><\/span><\/h2>\n[\/split_line_heading][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;none&#8221;]ABAP developers create or expand easily per drag and drop individual HTML5 applications with the MSB FIVE Application Builder. This is done very quickly thanks to the graphical editor \u2013 with minimal training effort. The adaptation of existing applications is also simple and flexible.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#007680&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#e2e2e2&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3><strong>Minimal adminstration effort<\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text]The MSB FIVE App is installed once and runs on any number of applications. Changes are automatically updated when the app restarts.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFF4DE&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#e2e2e2&#8243; column_border_style=&#8221;solid&#8221; delay=&#8221;300&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3><strong>Independently applicable<\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text]The MSB FIVE App can be used on any device with modern operating systems (Android, iOS, Win10).[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#0085CA&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;2px&#8221; column_border_color=&#8221;#e2e2e2&#8243; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221; border_animation_delay=&#8221;600&#8243; delay=&#8221;600&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3><strong>Responsive design<\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text]Not only is it possible to use a variety of hardware \u2013 it\u2019s fun. The display of the screens adapts automatically. Up or down. Huge or small.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#D9EBEC&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#e2e2e2&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3><strong>Modern Look &amp; Feel\u00a0<\/strong><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text]The appealing design and device control via swiping technology ensure rapid acceptance by the users.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#e2e2e2&#8243; column_border_style=&#8221;solid&#8221; delay=&#8221;300&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3><strong>Intelligent user guidance<\/strong><span style=\"color: #0085ca;\"><br \/>\n<\/span><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text]The MSB FIVE App guides the user intuitively through the processes. Data is thus easily collected in high quality.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#D9EDF7&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#e2e2e2&#8243; column_border_style=&#8221;solid&#8221; delay=&#8221;600&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3><strong>Integration of device features<\/strong><span style=\"color: #0085ca;\"><br \/>\n<\/span><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_column_text]Through the targeted use of device features, such as scanner, camera, RFID\/NFC and GPS, the full potential of mobile devices is exhausted.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#eeeeee&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; top_padding_phone=&#8221;10%&#8221; bottom_padding_phone=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; right_padding_phone=&#8221;10%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient=&#8221;linear-gradient(95deg, rgba(154,207,234,0.885) 0%, rgba(0,133,202,0.894) 22%, rgba(20,139,148,0.909) 74%)&#8221; advanced_gradient_angle=&#8221;95&#8243; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#FFFFFF&#8221; shape_divider_position=&#8221;both&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;advanced&#8221; shape_type=&#8221;tilt_alt&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][vc_column column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][split_line_heading animation_type=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<h2 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"28\" data-lineheight=\"38.92px\">What makes <strong><span style=\"color: #000000;\">MSB FIVE unique?<\/span><\/strong><\/h2>\n[\/split_line_heading][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first\">\n<div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\">\n<div class=\"fusion-text fusion-text-2\">\n<p>Learn more about our product and how you can efficiently mobilize your SAP processes with it in the product video. Please contact us for a detailed product demo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;see-through-2&#8243; hover_color_override=&#8221;#ffffff&#8221; hover_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;Jetzt kontaktieren&#8221; url=&#8221;\/contact&#8221; css_animation=&#8221;none&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html css=&#8221;&#8221;]JTNDaWZyYW1lJTIwd2lkdGglM0QlMjI1NjAlMjIlMjBoZWlnaHQlM0QlMjIzMTUlMjIlMjBzcmMlM0QlMjJodHRwcyUzQSUyRiUyRnd3dy55b3V0dWJlLmNvbSUyRmVtYmVkJTJGQXFoV2I3c3IyZGclM0ZzaSUzRFc2elc4SDhUc0F3ZGd5b0wlMjIlMjB0aXRsZSUzRCUyMllvdVR1YmUlMjB2aWRlbyUyMHBsYXllciUyMiUyMGZyYW1lYm9yZGVyJTNEJTIyMCUyMiUyMGFsbG93JTNEJTIyYWNjZWxlcm9tZXRlciUzQiUyMGF1dG9wbGF5JTNCJTIwY2xpcGJvYXJkLXdyaXRlJTNCJTIwZW5jcnlwdGVkLW1lZGlhJTNCJTIwZ3lyb3Njb3BlJTNCJTIwcGljdHVyZS1pbi1waWN0dXJlJTNCJTIwd2ViLXNoYXJlJTIyJTIwcmVmZXJyZXJwb2xpY3klM0QlMjJzdHJpY3Qtb3JpZ2luLXdoZW4tY3Jvc3Mtb3JpZ2luJTIyJTIwYWxsb3dmdWxsc2NyZWVuJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][nectar_global_section id=&#8221;2397&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\">\n<div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\">\n<h2 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"28\" data-lineheight=\"38.92px\">An example from <strong>maintenance<\/strong><\/h2>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flickity_style&#8221; images=&#8221;3083,3085,3087,3089,3091,3093,3095,3097,3099,3101,3081&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;next_prev_arrows&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_desktop_columns=&#8221;3&#8243; flickity_small_desktop_columns=&#8221;1&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_phone_columns=&#8221;1&#8243; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221; img_size=&#8221;312&#215;554&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#000000&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;100&#8243; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;tilt_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;1592&#8243;][\/vc_column][\/vc_row]\n<div class=\"shariff shariff-align-center shariff-widget-align-center\"><div class=\"ShariffHeadline\"><h3 style=\"text-align: center\">Teile diesen Beitrag<\/h3><\/div><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fmobisys.com%2Fen%2Fmsb-five%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fmobisys.com%2Fen%2Fmsb-five%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fmobisys.com%2Fen%2Fmsb-five%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fmobisys.com%2Fen%2Fmsb-five%2F%20MSB%20FIVE\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Wenn Sie einen der Links klicken, wird eine Verbindung zu dem Server des sozialen Netzwerkes hergestellt. Bitte beachten Sie unsere Datenschutzerkl\u00e4rung.\" aria-label=\"Wenn Sie einen der Links klicken, wird eine Verbindung zu dem Server des sozialen Netzwerkes hergestellt. Bitte beachten Sie unsere Datenschutzerkl\u00e4rung.\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;15%&#8221; bottom_padding_phone=&#8221;15%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient=&#8221;linear-gradient(95deg, rgba(0,133,202,0.53) 0%, rgba(0,133,202,0.869) 29%, rgba(0,118,128,0.878) 86%)&#8221; advanced_gradient_angle=&#8221;95&#8243; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#000000&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1484,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2384","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Smart mobile SAP processes with MSB FIVE<\/title>\n<meta name=\"description\" content=\"With little development effort to mobile SAP applications for maintenance processes for an optimal user experience.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobisys.com\/en\/msb-five\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart mobile SAP processes with MSB FIVE\" \/>\n<meta property=\"og:description\" content=\"With little development effort to mobile SAP applications for maintenance processes for an optimal user experience.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobisys.com\/en\/msb-five\/\" \/>\n<meta property=\"og:site_name\" content=\"mobisys GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mobisysgmbh\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-08T08:05:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mobisys.com\/wp-content\/uploads\/2022\/05\/Hamburger_Hafen_Video_Background.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1078\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/\",\"url\":\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/\",\"name\":\"Smart mobile SAP processes with MSB FIVE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mobisys.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mobisys.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Hamburger_Hafen_Video_Background.png\",\"datePublished\":\"2022-04-22T10:04:51+00:00\",\"dateModified\":\"2025-08-08T08:05:59+00:00\",\"description\":\"With little development effort to mobile SAP applications for maintenance processes for an optimal user experience.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mobisys.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Hamburger_Hafen_Video_Background.png\",\"contentUrl\":\"https:\\\/\\\/mobisys.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Hamburger_Hafen_Video_Background.png\",\"width\":1078,\"height\":667,\"caption\":\"Mobile Instandhaltung am Hamburger Hafen mit MSB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mobisys.com\\\/en\\\/msb-five\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mobisys.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MSB FIVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mobisys.com\\\/#website\",\"url\":\"https:\\\/\\\/mobisys.com\\\/\",\"name\":\"mobisys GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mobisys.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mobisys.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mobisys.com\\\/#organization\",\"name\":\"mobisys GmbH\",\"url\":\"https:\\\/\\\/mobisys.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mobisys.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mobisys.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/mobisys_Logo_Website.png\",\"contentUrl\":\"https:\\\/\\\/mobisys.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/mobisys_Logo_Website.png\",\"width\":195,\"height\":70,\"caption\":\"mobisys GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/mobisys.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mobisysgmbh\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2372698\\\/admin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smart mobile SAP processes with MSB FIVE","description":"With little development effort to mobile SAP applications for maintenance processes for an optimal user experience.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobisys.com\/en\/msb-five\/","og_locale":"en_US","og_type":"article","og_title":"Smart mobile SAP processes with MSB FIVE","og_description":"With little development effort to mobile SAP applications for maintenance processes for an optimal user experience.","og_url":"https:\/\/mobisys.com\/en\/msb-five\/","og_site_name":"mobisys GmbH","article_publisher":"https:\/\/www.facebook.com\/mobisysgmbh","article_modified_time":"2025-08-08T08:05:59+00:00","og_image":[{"width":1078,"height":667,"url":"https:\/\/mobisys.com\/wp-content\/uploads\/2022\/05\/Hamburger_Hafen_Video_Background.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mobisys.com\/en\/msb-five\/","url":"https:\/\/mobisys.com\/en\/msb-five\/","name":"Smart mobile SAP processes with MSB FIVE","isPartOf":{"@id":"https:\/\/mobisys.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobisys.com\/en\/msb-five\/#primaryimage"},"image":{"@id":"https:\/\/mobisys.com\/en\/msb-five\/#primaryimage"},"thumbnailUrl":"https:\/\/mobisys.com\/wp-content\/uploads\/2022\/05\/Hamburger_Hafen_Video_Background.png","datePublished":"2022-04-22T10:04:51+00:00","dateModified":"2025-08-08T08:05:59+00:00","description":"With little development effort to mobile SAP applications for maintenance processes for an optimal user experience.","breadcrumb":{"@id":"https:\/\/mobisys.com\/en\/msb-five\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobisys.com\/en\/msb-five\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mobisys.com\/en\/msb-five\/#primaryimage","url":"https:\/\/mobisys.com\/wp-content\/uploads\/2022\/05\/Hamburger_Hafen_Video_Background.png","contentUrl":"https:\/\/mobisys.com\/wp-content\/uploads\/2022\/05\/Hamburger_Hafen_Video_Background.png","width":1078,"height":667,"caption":"Mobile Instandhaltung am Hamburger Hafen mit MSB"},{"@type":"BreadcrumbList","@id":"https:\/\/mobisys.com\/en\/msb-five\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mobisys.com\/en\/"},{"@type":"ListItem","position":2,"name":"MSB FIVE"}]},{"@type":"WebSite","@id":"https:\/\/mobisys.com\/#website","url":"https:\/\/mobisys.com\/","name":"mobisys GmbH","description":"","publisher":{"@id":"https:\/\/mobisys.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobisys.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mobisys.com\/#organization","name":"mobisys GmbH","url":"https:\/\/mobisys.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mobisys.com\/#\/schema\/logo\/image\/","url":"https:\/\/mobisys.com\/wp-content\/uploads\/2022\/05\/mobisys_Logo_Website.png","contentUrl":"https:\/\/mobisys.com\/wp-content\/uploads\/2022\/05\/mobisys_Logo_Website.png","width":195,"height":70,"caption":"mobisys GmbH"},"image":{"@id":"https:\/\/mobisys.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mobisysgmbh","https:\/\/www.linkedin.com\/company\/2372698\/admin\/"]}]}},"_links":{"self":[{"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/pages\/2384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/comments?post=2384"}],"version-history":[{"count":18,"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/pages\/2384\/revisions"}],"predecessor-version":[{"id":8799,"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/pages\/2384\/revisions\/8799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/media\/1484"}],"wp:attachment":[{"href":"https:\/\/mobisys.com\/en\/wp-json\/wp\/v2\/media?parent=2384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}